{"id":342,"count":321,"description":"","link":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/","name":"Actualit\u00e9s","slug":"actualites","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualit\u00e9s Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualit\u00e9s Archives -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/category\\\/actualites\\\/\",\"url\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/category\\\/actualites\\\/\",\"name\":\"Actualit\u00e9s Archives -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/category\\\/actualites\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/category\\\/actualites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/\",\"name\":\"\",\"description\":\"M\u00e9dia g\u00e9n\u00e9raliste\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apres-lecole.fr\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualit\u00e9s Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/","og_locale":"fr_FR","og_type":"article","og_title":"Actualit\u00e9s Archives -","og_url":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/","url":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/","name":"Actualit\u00e9s Archives -","isPartOf":{"@id":"https:\/\/www.apres-lecole.fr\/Blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.apres-lecole.fr\/Blog\/category\/actualites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apres-lecole.fr\/Blog\/"},{"@type":"ListItem","position":2,"name":"Actualit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.apres-lecole.fr\/Blog\/#website","url":"https:\/\/www.apres-lecole.fr\/Blog\/","name":"","description":"M\u00e9dia g\u00e9n\u00e9raliste","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apres-lecole.fr\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.apres-lecole.fr\/Blog\/wp-json\/wp\/v2\/categories\/342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apres-lecole.fr\/Blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.apres-lecole.fr\/Blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.apres-lecole.fr\/Blog\/wp-json\/wp\/v2\/posts?categories=342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}